{"id":36613,"date":"2021-06-29T11:00:50","date_gmt":"2021-06-29T11:00:50","guid":{"rendered":"https:\/\/www.logicbus.com.mx\/blog\/?p=36613"},"modified":"2023-04-07T17:32:34","modified_gmt":"2023-04-07T17:32:34","slug":"normas-para-soldaduras-con-celda-de-carga","status":"publish","type":"post","link":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/","title":{"rendered":"Instalaci\u00f3n de Celdas de Carga."},"content":{"rendered":"<h3><strong>4. Normas para soldaduras con celda de carga sin da\u00f1arla<\/strong><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En las soldaduras el\u00e9ctricas se recomienda no soldar con la <span style=\"color: #000080;\" data-darkreader-inline-color=\"\"><strong><a style=\"color: #000080;\" href=\"https:\/\/www.logicbus.com.mx\/celdas-de-carga\" data-darkreader-inline-color=\"\">celda de carga<\/a><\/strong><\/span> ya montada.<\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\">\n<h5><strong>En caso de que esto sea inevitable<\/strong><\/h5>\n<\/li>\n<\/ul>\n<p align=\"justify\"><span style=\"font-weight: 400;\">Coloca la pinza positiva de la soldadura lo m\u00e1s cerca posible del punto donde se desea soldar para evitar el paso de corriente a trav\u00e9s del cuerpo de la <span style=\"color: #000080;\" data-darkreader-inline-color=\"\"><strong><a style=\"color: #000080;\" href=\"https:\/\/www.logicbus.com.mx\/celdas-de-carga\" data-darkreader-inline-color=\"\">celda<\/a><\/strong><\/span> que la da\u00f1ar\u00eda.<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-36614\" src=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_10-59-24-2-300x169.jpg\" alt=\"soldadura celda\" width=\"318\" height=\"179\" srcset=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_10-59-24-2-300x169.jpg 300w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_10-59-24-2-1024x576.jpg 1024w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_10-59-24-2-150x84.jpg 150w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_10-59-24-2-768x432.jpg 768w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_10-59-24-2.jpg 1366w\" sizes=\"(max-width: 318px) 100vw, 318px\" \/> <img decoding=\"async\" class=\"alignnone wp-image-36615\" src=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_11-01-34-1-300x169.jpg\" alt=\"soldadura celda\" width=\"312\" height=\"176\" srcset=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_11-01-34-1-300x169.jpg 300w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_11-01-34-1-1024x576.jpg 1024w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_11-01-34-1-150x84.jpg 150w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_11-01-34-1-768x432.jpg 768w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/2021-04-23_11-01-34-1.jpg 1366w\" sizes=\"(max-width: 312px) 100vw, 312px\" \/><\/p>\n<div id=\"part1737850\" class=\"P13\">\n<ul>\n<li>\n<h5>Arco el\u00e9ctrico<\/h5>\n<\/li>\n<\/ul>\n<p align=\"justify\">El arco el\u00e9ctrico es uno de los principales riesgos a los que se ven expuestos los trabajadores de instalaciones el\u00e9ctricas. Cuando se produce un arco, se desencadena una fuerte liberaci\u00f3n de energ\u00eda y se producen muchos fen\u00f3menos diferentes. Actualmente, el riesgo t\u00e9rmico asociado al arco es el riesgo en el que m\u00e1s se ha avanzado y sobre el que se han planteado m\u00e1s medidas preventivas.<\/p>\n<ul>\n<li>\n<h5>Riesgos<\/h5>\n<\/li>\n<\/ul>\n<p align=\"justify\">En la evaluaci\u00f3n frente a los riesgos t\u00e9rmicos asociados al arco, es fundamental establecer dos elementos: la zona de peligro frente al arco, a trav\u00e9s del \u2018l\u00edmite de seguridad frente al arco\u2019 (FPB) y una estimaci\u00f3n de la energ\u00eda calor\u00edfica incidente sobre los trabajadores dentro de dicha zona.<\/p>\n<\/div>\n<div id=\"part1737853\" class=\"P2\" style=\"text-align: justify;\">\n<p align=\"justify\">Se denomina arco el\u00e9ctrico a la descarga el\u00e9ctrica que se forma entre dos electrodos sometidos a una diferencia de potencial.<\/p>\n<\/div>\n<ul>\n<li>\n<h5>Descarga disruptiva<\/h5>\n<\/li>\n<\/ul>\n<div class=\"P2\" style=\"text-align: justify;\">\n<p align=\"justify\">Un arco el\u00e9ctrico es una descarga disruptiva generada por la ionizaci\u00f3n de gas como consecuencia de una conexi\u00f3n accidental el\u00e9ctrica entre dos superficies o elementos de diferente potencial, de diferente posici\u00f3n de fase o entre un electrodo y un circuito de tierra.<\/p>\n<\/div>\n<div class=\"P2\" style=\"text-align: justify;\">\n<p align=\"justify\">Cuando el arco el\u00e9ctrico en una instalaci\u00f3n o en un equipo el\u00e9ctrico no ha sido planificado sino que surge a causa de una perturbaci\u00f3n, entonces se trata de un arco el\u00e9ctrico perturbador. \u00c9ste puede ser causado por un fallo t\u00e9cnico o por un error humano, en la mayor\u00eda de ocasiones, (ca\u00edda de herramientas, maniobra inadecuada, etc.).<\/p>\n<\/div>\n<h5 style=\"text-align: justify;\">Ejemplo de da\u00f1o por arco el\u00e9ctrico :<\/h5>\n<div><img decoding=\"async\" class=\"size-medium wp-image-36885 aligncenter\" src=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-1-223x300.jpg\" alt=\"\" width=\"223\" height=\"300\" srcset=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-1-223x300.jpg 223w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-1-762x1024.jpg 762w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-1-112x150.jpg 112w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-1-768x1032.jpg 768w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-1-1143x1536.jpg 1143w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-1.jpg 1319w\" sizes=\"(max-width: 223px) 100vw, 223px\" \/><\/div>\n<div><\/div>\n<div><img decoding=\"async\" class=\" wp-image-36886 aligncenter\" src=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-2-300x171.jpeg\" alt=\"\" width=\"328\" height=\"187\" srcset=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-2-300x171.jpeg 300w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-2-150x86.jpeg 150w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-2-768x439.jpeg 768w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/04\/dano-por-arco-electrico-2.jpeg 875w\" sizes=\"(max-width: 328px) 100vw, 328px\" \/><\/div>\n<p>&nbsp;<\/p>\n<p align=\"justify\"><span style=\"color: #000080;\" data-darkreader-inline-color=\"\"><strong><a style=\"color: #000080;\" href=\"https:\/\/www.logicbus.com.mx\/celdas-de-carga\" data-darkreader-inline-color=\"\">Logicbus<\/a><\/strong><\/span> esta sujeto a normas de garant\u00edas, si tiene dudas con la garant\u00eda de celdas de carga lo mas recomendable es ponerse en contacto para resolver dudas acerca de la garant\u00eda de las celdas.<\/p>\n<p>Si tienes dudas en alg\u00fan punto o requieres mas ayuda con gusto te asesoramos en <strong><a href=\"mailto:soporte@logicbus.com\">soporte@logicbus.com<\/a><\/strong><\/p>\n<h3 style=\"text-align: center;\">Cont\u00e1ctanos<\/h3>\n<hr \/>\n<p><img decoding=\"async\" class=\"alignnone wp-image-37978\" src=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-ventas-300x300.png\" alt=\"contacto para la empresa via email\" width=\"95\" height=\"95\" srcset=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-ventas-300x300.png 300w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-ventas-150x150.png 150w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-ventas-24x24.png 24w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-ventas-48x48.png 48w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-ventas-96x96.png 96w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-ventas.png 500w\" sizes=\"(max-width: 95px) 100vw, 95px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"mailto:soporte@logicbus.com\"><img decoding=\"async\" class=\"alignnone wp-image-37979\" src=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-soporte-300x300.png\" alt=\"contacto a la empresa via email de soporte\" width=\"96\" height=\"96\" srcset=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-soporte-300x300.png 300w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-soporte-150x150.png 150w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-soporte-24x24.png 24w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-soporte-48x48.png 48w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-soporte-96x96.png 96w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/email-de-soporte.png 500w\" sizes=\"(max-width: 96px) 100vw, 96px\" \/><\/a>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<a href=\"https:\/\/api.whatsapp.com\/send?phone=525554316718&amp;text=Hola%20Logicbus,me%20gustar%C3%ADa%20solicitar%20informaci%C3%B3n\"><img decoding=\"async\" class=\"alignnone wp-image-37980\" src=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/whatsapp-empresa-300x300.png\" alt=\"contacto con la empresa via red social\" width=\"96\" height=\"96\" srcset=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/whatsapp-empresa-300x300.png 300w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/whatsapp-empresa-150x150.png 150w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/whatsapp-empresa-24x24.png 24w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/whatsapp-empresa-48x48.png 48w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/whatsapp-empresa-96x96.png 96w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/whatsapp-empresa.png 500w\" sizes=\"(max-width: 96px) 100vw, 96px\" \/><\/a>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <a href=\"https:\/\/tawk.to\/chat\/5ca674ff1de11b6e3b06f73d\/default\"><img decoding=\"async\" class=\"alignnone wp-image-37981\" src=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/chat-online-300x300.png\" alt=\"contacto con la empresa via chat online\" width=\"96\" height=\"96\" srcset=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/chat-online-300x300.png 300w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/chat-online-150x150.png 150w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/chat-online-24x24.png 24w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/chat-online-48x48.png 48w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/chat-online-96x96.png 96w, https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/chat-online.png 500w\" sizes=\"(max-width: 96px) 100vw, 96px\" \/><\/a><\/p>\n<p><a href=\"mailto:ventas@logicbus.com\">ventas@logicbus.com<\/a>\u00a0| \u00a0<a href=\"mailto:soporte@logicbus.com\">soporte@logicbus.com<\/a>\u00a0 \u00a0|\u00a0 \u00a0<a href=\"https:\/\/api.whatsapp.com\/send?phone=525554316718&amp;text=Hola%20Logicbus,me%20gustar%C3%ADa%20solicitar%20informaci%C3%B3n\">55-5431-6718\u00a0<\/a>\u00a0 \u00a0 | \u00a0\u00a0\u00a0<a href=\"https:\/\/tawk.to\/chat\/5ca674ff1de11b6e3b06f73d\/default\">Iniciar conversaci\u00f3n<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>4. Normas para soldaduras con celda de carga sin da\u00f1arla En las soldaduras el\u00e9ctricas se recomienda no soldar con la celda de carga ya montada. En caso de que esto sea inevitable Coloca la pinza positiva de la soldadura lo m\u00e1s cerca posible del punto donde se desea soldar para evitar el paso de corriente [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":40089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5534,5765,5535],"tags":[],"class_list":["post-36613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aplicaciones-de-automatizacion-en-la-industria","category-celdas-de-carga-y-electronica-de-pesaje","category-informacion-tecnica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Normas para soldaduras con celda de carga - Logicbus<\/title>\n<meta name=\"description\" content=\"En las soldaduras el\u00e9ctricas se recomienda no soldar con las celda de carga ya montada. Coloca la pinza positiva de la soldadura lo m\u00e1s cerca posible ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Normas para soldaduras con celda de carga - Logicbus\" \/>\n<meta property=\"og:description\" content=\"En las soldaduras el\u00e9ctricas se recomienda no soldar con las celda de carga ya montada. Coloca la pinza positiva de la soldadura lo m\u00e1s cerca posible ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Logicbus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/logicbus\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-29T11:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-07T17:32:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/BANNER.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Josue Cetina\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Josue Cetina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Normas para soldaduras con celda de carga - Logicbus","description":"En las soldaduras el\u00e9ctricas se recomienda no soldar con las celda de carga ya montada. Coloca la pinza positiva de la soldadura lo m\u00e1s cerca posible ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/","og_locale":"es_MX","og_type":"article","og_title":"Normas para soldaduras con celda de carga - Logicbus","og_description":"En las soldaduras el\u00e9ctricas se recomienda no soldar con las celda de carga ya montada. Coloca la pinza positiva de la soldadura lo m\u00e1s cerca posible ...","og_url":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/","og_site_name":"Blog Logicbus","article_publisher":"https:\/\/www.facebook.com\/logicbus\/","article_published_time":"2021-06-29T11:00:50+00:00","article_modified_time":"2023-04-07T17:32:34+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/BANNER.png","type":"image\/png"}],"author":"Josue Cetina","twitter_misc":{"Escrito por":"Josue Cetina","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/#article","isPartOf":{"@id":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/"},"author":{"name":"Josue Cetina","@id":"https:\/\/www.logicbus.com.mx\/blog\/#\/schema\/person\/d2f308e65be01c1b9ab007719614b6a7"},"headline":"Instalaci\u00f3n de Celdas de Carga.","datePublished":"2021-06-29T11:00:50+00:00","dateModified":"2023-04-07T17:32:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/"},"wordCount":422,"commentCount":0,"publisher":{"@id":"https:\/\/www.logicbus.com.mx\/blog\/#organization"},"image":{"@id":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/BANNER.png","articleSection":["Aplicaciones","Celdas de Carga y electr\u00f3nica de pesaje","Informaci\u00f3n T\u00e9cnica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/","url":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/","name":"Normas para soldaduras con celda de carga - Logicbus","isPartOf":{"@id":"https:\/\/www.logicbus.com.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/#primaryimage"},"image":{"@id":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/BANNER.png","datePublished":"2021-06-29T11:00:50+00:00","dateModified":"2023-04-07T17:32:34+00:00","description":"En las soldaduras el\u00e9ctricas se recomienda no soldar con las celda de carga ya montada. Coloca la pinza positiva de la soldadura lo m\u00e1s cerca posible ...","breadcrumb":{"@id":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/#primaryimage","url":"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/BANNER.png","contentUrl":"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/06\/BANNER.png","width":1920,"height":1080,"caption":"Normas para soldaduras con celda de carga sin da\u00f1arla"},{"@type":"BreadcrumbList","@id":"https:\/\/www.logicbus.com.mx\/blog\/normas-para-soldaduras-con-celda-de-carga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.logicbus.com.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Instalaci\u00f3n de Celdas de Carga."}]},{"@type":"WebSite","@id":"https:\/\/www.logicbus.com.mx\/blog\/#website","url":"https:\/\/www.logicbus.com.mx\/blog\/","name":"Blog Logicbus","description":"Logicbus Blog ofrece informaci\u00f3n detallada sobre el control de procesos, sus tipos, elementos e importancia.","publisher":{"@id":"https:\/\/www.logicbus.com.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.logicbus.com.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.logicbus.com.mx\/blog\/#organization","name":"Logicbus Blog","url":"https:\/\/www.logicbus.com.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.logicbus.com.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/03\/logo-logicbus-blog.png","contentUrl":"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/03\/logo-logicbus-blog.png","width":1761,"height":546,"caption":"Logicbus Blog"},"image":{"@id":"https:\/\/www.logicbus.com.mx\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/logicbus\/","https:\/\/x.com\/Logicbus"]},{"@type":"Person","@id":"https:\/\/www.logicbus.com.mx\/blog\/#\/schema\/person\/d2f308e65be01c1b9ab007719614b6a7","name":"Josue Cetina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/03\/JosueCetina-96x96.png","url":"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/03\/JosueCetina-96x96.png","contentUrl":"https:\/\/www.logicbus.com.mx\/blog\/wp-content\/uploads\/2021\/03\/JosueCetina-96x96.png","caption":"Josue Cetina"},"url":"https:\/\/www.logicbus.com.mx\/blog\/author\/josue-cetina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.logicbus.com.mx\/blog\/wp-json\/wp\/v2\/posts\/36613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.logicbus.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.logicbus.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.logicbus.com.mx\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.logicbus.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=36613"}],"version-history":[{"count":0,"href":"https:\/\/www.logicbus.com.mx\/blog\/wp-json\/wp\/v2\/posts\/36613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.logicbus.com.mx\/blog\/wp-json\/wp\/v2\/media\/40089"}],"wp:attachment":[{"href":"https:\/\/www.logicbus.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=36613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.logicbus.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=36613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.logicbus.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=36613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}